{"id":2012,"date":"2011-11-23T10:58:00","date_gmt":"2011-11-23T09:58:00","guid":{"rendered":"http:\/\/basisinkomen.nl\/wp\/?p=2012"},"modified":"2011-11-23T10:58:00","modified_gmt":"2011-11-23T09:58:00","slug":"het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen","status":"publish","type":"post","link":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/","title":{"rendered":"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen"},"content":{"rendered":"<p><strong>Het basisinkomen als erkenning van de menselijke waardigheid.<\/strong><\/p>\n<p>Klik je Universeel basisinkomen aan op google, dan krijg je 1370 resultaten in het Nederlands, voor Allocation universelle in het Frans zijn dat er 63.600, het Duitse Grundeinkommen levert dan weer 725.000 resultaten op en het Engelse Basic Income biedt er 4.730.000 aan. Dat was in oktober vorig jaar. Vandaag anno 2011 zijn er weer tal van sites bijgekomen. Met &#8216;dank&#8217; aan de crisis&#8230;.want we beginnen na te denken, samen met de Indignado&#8217;s, Wall Street bezetters en ja zelfs topeconomen.<\/p>\n<p>Deze sites behoren toe aan bekende en minder bekende netwerken, aan leerstoelen van grote universiteiten en ze worden bijgehouden door academici, politici, denkers, filosofen, andersglobalisten, op facebook en twitter, via blogs en fora, door utopisten, dromers, economen, gewone mensen&#8230; ook wij dus: u en ik. Heel wat mensen die zich van dichtbij of van veraf interesseren voor het onvoorwaardelijk basisinkomen.<!--more--><\/p>\n<p>Er is dus al zoveel te lezen over het universeel onvoorwaardelijk basisinkomen, waarom dan nog meer ?<\/p>\n<p>&#8230; om er eindelijk misschien iets van te begrijpen&#8230;.?<\/p>\n<p>Hier willen we ons dus vooral de vragen stellen die we ons allemaal wel eens stellen, maar niet luidop durven formuleren. Want als je tegenwoordig over het onvoorwaardelijk basisinkomen spreekt, word je eerst meewarig bekeken en word je ook meteen verkast naar de groep niet-werkwillige dromers die ergens in de hippy-jaren bleven hangen en samenhokken in commune&#8217;s terwijl ze rondlopen in open sandalen met geitewollensokken.<\/p>\n<p>Een vraag die we ook zelden luidop durven formuleren: waarom werken we?<\/p>\n<p>Werken en een onvoorwaardelijk basisinkomen gaan namelijk hand in hand, of u het nu gelooft of niet.<\/p>\n<p><em>Dus om te beginnen: waarom werken we?<\/em><\/p>\n<p>Lees dat verder in het artikel op de website van ECOVA<\/p>\n<p>Bron:\u00a0<a href=\"http:\/\/www.ecovaproject.org\/basisinkomen-menselijke-waardigheid.htm\"  target=\"_blank\" rel=\"external nofollow\"  title=\"http:\/\/www.ecovaproject.org\/basisinkomen-menselijke-waardigheid.htm\"  class=\"wp-links-icon\">http:\/\/www.ecovaproject.org\/basisinkomen-menselijke-waardigheid.htm<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Het basisinkomen als erkenning van de menselijke waardigheid. Klik je Universeel basisinkomen aan op google, dan krijg je 1370 resultaten in het Nederlands, voor Allocation universelle in het Frans zijn dat er 63.600, het Duitse Grundeinkommen levert dan weer 725.000 resultaten op en het Engelse Basic Income biedt er 4.730.000 aan. Dat was in oktober vorig jaar. Vandaag anno 2011 zijn er weer tal van sites bijgekomen. Met &#8216;dank&#8217; aan de crisis&#8230;.want we beginnen na te denken, samen met de Indignado&#8217;s, Wall Street bezetters en ja zelfs topeconomen. Deze sites behoren toe aan bekende en minder bekende netwerken, aan leerstoelen van grote universiteiten en ze worden bijgehouden door academici, politici, [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7,56,10,4],"tags":[],"class_list":["post-2012","post","type-post","status-publish","format-standard","hentry","category-buitenlands-nieuws","category-geschiedenis","category-opinie","category-studie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen - onvoorwaardelijk Basisinkomen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen - onvoorwaardelijk Basisinkomen\" \/>\n<meta property=\"og:description\" content=\"Het basisinkomen als erkenning van de menselijke waardigheid. Klik je Universeel basisinkomen aan op google, dan krijg je 1370 resultaten in het Nederlands, voor Allocation universelle in het Frans zijn dat er 63.600, het Duitse Grundeinkommen levert dan weer 725.000 resultaten op en het Engelse Basic Income biedt er 4.730.000 aan. Dat was in oktober vorig jaar. Vandaag anno 2011 zijn er weer tal van sites bijgekomen. Met &#8216;dank&#8217; aan de crisis&#8230;.want we beginnen na te denken, samen met de Indignado&#8217;s, Wall Street bezetters en ja zelfs topeconomen. Deze sites behoren toe aan bekende en minder bekende netwerken, aan leerstoelen van grote universiteiten en ze worden bijgehouden door academici, politici, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/\" \/>\n<meta property=\"og:site_name\" content=\"onvoorwaardelijk Basisinkomen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basisinkomen.net\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-23T09:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/basisinkomen.org\/obi\/wp-content\/uploads\/2015\/06\/binet-aquare200.jpg?fit=200%2C200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@basisinkomen\" \/>\n<meta name=\"twitter:site\" content=\"@basisinkomen\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#\\\/schema\\\/person\\\/e7c72461bffa22b196f4aca8d778e8d2\"},\"headline\":\"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen\",\"datePublished\":\"2011-11-23T09:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/\"},\"wordCount\":301,\"articleSection\":[\"Buitenlands Nieuws\",\"Geschiedenis\",\"Opinie\",\"Studie\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/\",\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/\",\"name\":\"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen - onvoorwaardelijk Basisinkomen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#website\"},\"datePublished\":\"2011-11-23T09:58:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#\\\/schema\\\/person\\\/e7c72461bffa22b196f4aca8d778e8d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#website\",\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/\",\"name\":\"onvoorwaardelijk Basisinkomen\",\"description\":\"Unconditional Basic Income\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#\\\/schema\\\/person\\\/e7c72461bffa22b196f4aca8d778e8d2\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen - onvoorwaardelijk Basisinkomen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/","og_locale":"nl_NL","og_type":"article","og_title":"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen - onvoorwaardelijk Basisinkomen","og_description":"Het basisinkomen als erkenning van de menselijke waardigheid. Klik je Universeel basisinkomen aan op google, dan krijg je 1370 resultaten in het Nederlands, voor Allocation universelle in het Frans zijn dat er 63.600, het Duitse Grundeinkommen levert dan weer 725.000 resultaten op en het Engelse Basic Income biedt er 4.730.000 aan. Dat was in oktober vorig jaar. Vandaag anno 2011 zijn er weer tal van sites bijgekomen. Met &#8216;dank&#8217; aan de crisis&#8230;.want we beginnen na te denken, samen met de Indignado&#8217;s, Wall Street bezetters en ja zelfs topeconomen. Deze sites behoren toe aan bekende en minder bekende netwerken, aan leerstoelen van grote universiteiten en ze worden bijgehouden door academici, politici, [&hellip;]","og_url":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/","og_site_name":"onvoorwaardelijk Basisinkomen","article_publisher":"https:\/\/www.facebook.com\/basisinkomen.net","article_published_time":"2011-11-23T09:58:00+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/i0.wp.com\/basisinkomen.org\/obi\/wp-content\/uploads\/2015\/06\/binet-aquare200.jpg?fit=200%2C200&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@basisinkomen","twitter_site":"@basisinkomen","twitter_misc":{"Geschreven door":"admin","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/#article","isPartOf":{"@id":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/"},"author":{"name":"admin","@id":"https:\/\/basisinkomen.org\/obi\/#\/schema\/person\/e7c72461bffa22b196f4aca8d778e8d2"},"headline":"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen","datePublished":"2011-11-23T09:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/"},"wordCount":301,"articleSection":["Buitenlands Nieuws","Geschiedenis","Opinie","Studie"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/","url":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/","name":"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen - onvoorwaardelijk Basisinkomen","isPartOf":{"@id":"https:\/\/basisinkomen.org\/obi\/#website"},"datePublished":"2011-11-23T09:58:00+00:00","author":{"@id":"https:\/\/basisinkomen.org\/obi\/#\/schema\/person\/e7c72461bffa22b196f4aca8d778e8d2"},"breadcrumb":{"@id":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/basisinkomen.org\/obi\/het-ecovaproject-pleit-voor-een-universele-sociale-zekerheid-en-een-onvoorwaardelijk-basisinkomen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/basisinkomen.org\/obi\/"},{"@type":"ListItem","position":2,"name":"Het ecovaproject pleit voor een universele sociale zekerheid en een onvoorwaardelijk basisinkomen"}]},{"@type":"WebSite","@id":"https:\/\/basisinkomen.org\/obi\/#website","url":"https:\/\/basisinkomen.org\/obi\/","name":"onvoorwaardelijk Basisinkomen","description":"Unconditional Basic Income","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basisinkomen.org\/obi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/basisinkomen.org\/obi\/#\/schema\/person\/e7c72461bffa22b196f4aca8d778e8d2","name":"admin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/basisinkomen.org\/obi\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6lJNg-ws","jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/posts\/2012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/comments?post=2012"}],"version-history":[{"count":0,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/posts\/2012\/revisions"}],"wp:attachment":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/media?parent=2012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/categories?post=2012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/tags?post=2012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}