{"id":5659,"date":"2014-05-27T11:55:46","date_gmt":"2014-05-27T09:55:46","guid":{"rendered":"http:\/\/basisinkomen.nl\/wp\/?p=5659"},"modified":"2014-05-27T11:55:46","modified_gmt":"2014-05-27T09:55:46","slug":"joeri-oltheten-het-basisinkomen-uab-congres-rond-geld","status":"publish","type":"post","link":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/","title":{"rendered":"Joeri Oltheten over het basisinkomen &#8211; UAB Congres Rond Geld"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/basisinkomen.nl\/wp\/wp-content\/uploads\/image\/joeri-oltheten.jpg\"  ><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5663\" src=\"https:\/\/i0.wp.com\/basisinkomen.nl\/wp\/wp-content\/uploads\/image\/joeri-oltheten.jpg?resize=183%2C275\" alt=\"joeri-oltheten\" width=\"183\" height=\"275\" \/><\/a>Joeri Oltheten bij het congres &#8216;Rond Geld&#8217; van de Universiteit voor het Algemeen Belang.<\/p>\n<p>Lezing van 30 april 2014 aan de Karel de Grote Hogeschool in Antwerpen<!--more--><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/9UAtz_L7Rmo\" width=\"540\" height=\"304\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joeri Oltheten bij het congres &#8216;Rond Geld&#8217; van de Universiteit voor het Algemeen Belang. Lezing van 30 april 2014 aan de Karel de Grote Hogeschool in Antwerpen<\/p>\n","protected":false},"author":14,"featured_media":5663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[857],"tags":[1634,1635],"class_list":["post-5659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verslagen","tag-antwerpen","tag-universiteit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joeri Oltheten over het basisinkomen - UAB Congres Rond Geld - onvoorwaardelijk Basisinkomen<\/title>\n<meta name=\"description\" content=\"Joeri Oltheten bij het congres &#039;Rond Geld&#039; van de Universiteit voor het Algemeen Belang. Lezing van 30 \/4\/2014 aan de Karel de Grote Hogeschool in Antwerpen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joeri Oltheten over het basisinkomen - UAB Congres Rond Geld - onvoorwaardelijk Basisinkomen\" \/>\n<meta property=\"og:description\" content=\"Joeri Oltheten bij het congres &#039;Rond Geld&#039; van de Universiteit voor het Algemeen Belang. Lezing van 30 \/4\/2014 aan de Karel de Grote Hogeschool in Antwerpen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/\" \/>\n<meta property=\"og:site_name\" content=\"onvoorwaardelijk Basisinkomen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basisinkomen.net\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-27T09:55:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/basisinkomen.org\/obi\/wp-content\/uploads\/2015\/06\/binet-aquare200.jpg?fit=200%2C200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@basisinkomen\" \/>\n<meta name=\"twitter:site\" content=\"@basisinkomen\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#\\\/schema\\\/person\\\/e7c72461bffa22b196f4aca8d778e8d2\"},\"headline\":\"Joeri Oltheten over het basisinkomen &#8211; UAB Congres Rond Geld\",\"datePublished\":\"2014-05-27T09:55:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/\"},\"wordCount\":35,\"image\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"antwerpen\",\"universiteit\"],\"articleSection\":[\"Verslagen\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/\",\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/\",\"name\":\"Joeri Oltheten over het basisinkomen - UAB Congres Rond Geld - onvoorwaardelijk Basisinkomen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2014-05-27T09:55:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#\\\/schema\\\/person\\\/e7c72461bffa22b196f4aca8d778e8d2\"},\"description\":\"Joeri Oltheten bij het congres 'Rond Geld' van de Universiteit voor het Algemeen Belang. Lezing van 30 \\\/4\\\/2014 aan de Karel de Grote Hogeschool in Antwerpen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joeri Oltheten over het basisinkomen &#8211; UAB Congres Rond Geld\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#website\",\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/\",\"name\":\"onvoorwaardelijk Basisinkomen\",\"description\":\"Unconditional Basic Income\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#\\\/schema\\\/person\\\/e7c72461bffa22b196f4aca8d778e8d2\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joeri Oltheten over het basisinkomen - UAB Congres Rond Geld - onvoorwaardelijk Basisinkomen","description":"Joeri Oltheten bij het congres 'Rond Geld' van de Universiteit voor het Algemeen Belang. Lezing van 30 \/4\/2014 aan de Karel de Grote Hogeschool in Antwerpen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/","og_locale":"nl_NL","og_type":"article","og_title":"Joeri Oltheten over het basisinkomen - UAB Congres Rond Geld - onvoorwaardelijk Basisinkomen","og_description":"Joeri Oltheten bij het congres 'Rond Geld' van de Universiteit voor het Algemeen Belang. Lezing van 30 \/4\/2014 aan de Karel de Grote Hogeschool in Antwerpen","og_url":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/","og_site_name":"onvoorwaardelijk Basisinkomen","article_publisher":"https:\/\/www.facebook.com\/basisinkomen.net","article_published_time":"2014-05-27T09:55:46+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/i0.wp.com\/basisinkomen.org\/obi\/wp-content\/uploads\/2015\/06\/binet-aquare200.jpg?fit=200%2C200&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@basisinkomen","twitter_site":"@basisinkomen","twitter_misc":{"Geschreven door":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/#article","isPartOf":{"@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/"},"author":{"name":"admin","@id":"https:\/\/basisinkomen.org\/obi\/#\/schema\/person\/e7c72461bffa22b196f4aca8d778e8d2"},"headline":"Joeri Oltheten over het basisinkomen &#8211; UAB Congres Rond Geld","datePublished":"2014-05-27T09:55:46+00:00","mainEntityOfPage":{"@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/"},"wordCount":35,"image":{"@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/#primaryimage"},"thumbnailUrl":"","keywords":["antwerpen","universiteit"],"articleSection":["Verslagen"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/","url":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/","name":"Joeri Oltheten over het basisinkomen - UAB Congres Rond Geld - onvoorwaardelijk Basisinkomen","isPartOf":{"@id":"https:\/\/basisinkomen.org\/obi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/#primaryimage"},"image":{"@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/#primaryimage"},"thumbnailUrl":"","datePublished":"2014-05-27T09:55:46+00:00","author":{"@id":"https:\/\/basisinkomen.org\/obi\/#\/schema\/person\/e7c72461bffa22b196f4aca8d778e8d2"},"description":"Joeri Oltheten bij het congres 'Rond Geld' van de Universiteit voor het Algemeen Belang. Lezing van 30 \/4\/2014 aan de Karel de Grote Hogeschool in Antwerpen","breadcrumb":{"@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/basisinkomen.org\/obi\/joeri-oltheten-het-basisinkomen-uab-congres-rond-geld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/basisinkomen.org\/obi\/"},{"@type":"ListItem","position":2,"name":"Joeri Oltheten over het basisinkomen &#8211; UAB Congres Rond Geld"}]},{"@type":"WebSite","@id":"https:\/\/basisinkomen.org\/obi\/#website","url":"https:\/\/basisinkomen.org\/obi\/","name":"onvoorwaardelijk Basisinkomen","description":"Unconditional Basic Income","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basisinkomen.org\/obi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/basisinkomen.org\/obi\/#\/schema\/person\/e7c72461bffa22b196f4aca8d778e8d2","name":"admin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fce5aa447e1b885711102be8d9df486a5eba89bf364313bd3ce1a07380f1405c?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/basisinkomen.org\/obi\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6lJNg-1th","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/posts\/5659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/comments?post=5659"}],"version-history":[{"count":0,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/posts\/5659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/media?parent=5659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/categories?post=5659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/tags?post=5659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}