{"id":1152,"count":3,"description":"","link":"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/","name":"fraude","slug":"fraude","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>fraude Archieven - onvoorwaardelijk Basisinkomen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"fraude Archieven - onvoorwaardelijk Basisinkomen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/\" \/>\n<meta property=\"og:site_name\" content=\"onvoorwaardelijk Basisinkomen\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/basisinkomen.org\/obi\/wp-content\/uploads\/2015\/06\/binet-aquare200.jpg?fit=200%2C200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@basisinkomen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/tag\\\/fraude\\\/\",\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/tag\\\/fraude\\\/\",\"name\":\"fraude Archieven - onvoorwaardelijk Basisinkomen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/tag\\\/fraude\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/tag\\\/fraude\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"fraude\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/#website\",\"url\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/\",\"name\":\"onvoorwaardelijk Basisinkomen\",\"description\":\"Unconditional Basic Income\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/basisinkomen.org\\\/obi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"fraude Archieven - onvoorwaardelijk Basisinkomen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/","og_locale":"nl_NL","og_type":"article","og_title":"fraude Archieven - onvoorwaardelijk Basisinkomen","og_url":"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/","og_site_name":"onvoorwaardelijk Basisinkomen","og_image":[{"width":200,"height":200,"url":"https:\/\/i0.wp.com\/basisinkomen.org\/obi\/wp-content\/uploads\/2015\/06\/binet-aquare200.jpg?fit=200%2C200&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@basisinkomen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/","url":"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/","name":"fraude Archieven - onvoorwaardelijk Basisinkomen","isPartOf":{"@id":"https:\/\/basisinkomen.org\/obi\/#website"},"breadcrumb":{"@id":"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/basisinkomen.org\/obi\/tag\/fraude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/basisinkomen.org\/obi\/"},{"@type":"ListItem","position":2,"name":"fraude"}]},{"@type":"WebSite","@id":"https:\/\/basisinkomen.org\/obi\/#website","url":"https:\/\/basisinkomen.org\/obi\/","name":"onvoorwaardelijk Basisinkomen","description":"Unconditional Basic Income","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basisinkomen.org\/obi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/tags\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/basisinkomen.org\/obi\/wp-json\/wp\/v2\/posts?tags=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}